{"id":6598,"date":"2016-03-18T16:06:36","date_gmt":"2016-03-18T16:06:36","guid":{"rendered":"http:\/\/andromeda-buecher.de\/buch2\/?product=weisheit-vom-orient-philosophische-betrachtungen-mit-einer-erlaeuterung-der-symbole-der-freimaurer"},"modified":"2016-03-24T14:34:51","modified_gmt":"2016-03-24T13:34:51","slug":"weisheit-vom-orient-philosophische-betrachtungen-mit-einer-erlaeuterung-der-symbole-der-freimaurer","status":"publish","type":"product","link":"http:\/\/andromeda-buecher.de\/buch2\/produkt\/weisheit-vom-orient-philosophische-betrachtungen-mit-einer-erlaeuterung-der-symbole-der-freimaurer\/","title":{"rendered":"Weisheit vom Orient: Philosophische Betrachtungen mit einer Erl\u00e4uterung der Symbole der Freimaurer"},"content":{"rendered":"<p>Kerning: &#8222;Weisheit vom Orient&#8220;<br \/>\nPhilosophische Betrachtungen<br \/>\nMit einer Erl\u00e4uterung der Freimauerer von Bruder O. G.<\/p>\n<p>232 Seiten, ISBN 3-928722-21-2, kartoniert, Schatzkammer, 1984<\/p>\n<p>Kerning: &#8222;Weisheit vom Orient&#8220;<br \/>\nPhilosophische Betrachtungen<br \/>\nMit einer Erl\u00e4uterung der Freimauerer von Bruder O. G. 232 Seiten.<\/p>\n<p>ISBN 3-928722-21-2 kartoniert<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kerning: &#8222;Weisheit vom Orient&#8220; Philosophische Betrachtungen Mit einer Erl\u00e4uterung der Freimauerer von Bruder O. G. 232 Seiten, ISBN 3-928722-21-2, kartoniert, Schatzkammer, 1984 Kerning: &#8222;Weisheit vom Orient&#8220; Philosophische Betrachtungen Mit einer Erl\u00e4uterung der Freimauerer von Bruder O. G. 232 Seiten. ISBN 3-928722-21-2 kartoniert<\/p>\n","protected":false},"featured_media":13285,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[127],"product_tag":[],"_links":{"self":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product\/6598"}],"collection":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/comments?post=6598"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/media\/13285"}],"wp:attachment":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/media?parent=6598"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product_cat?post=6598"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product_tag?post=6598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}