{"id":10380,"date":"2016-03-19T17:09:11","date_gmt":"2016-03-19T17:09:11","guid":{"rendered":"http:\/\/andromeda-buecher.de\/buch2\/shop\/der-lebensmagnetismus-seine-erscheinungen-und-seine-praxis-seine-anwendung-zur-heilung-der-verschiedensten-krankheiten\/"},"modified":"2016-03-19T17:09:11","modified_gmt":"2016-03-19T17:09:11","slug":"der-lebensmagnetismus-seine-erscheinungen-und-seine-praxis-seine-anwendung-zur-heilung-der-verschiedensten-krankheiten","status":"publish","type":"product","link":"http:\/\/andromeda-buecher.de\/buch2\/produkt\/der-lebensmagnetismus-seine-erscheinungen-und-seine-praxis-seine-anwendung-zur-heilung-der-verschiedensten-krankheiten\/","title":{"rendered":"Der Lebensmagnetismus seine Erscheinungen und seine Praxis: Seine Anwendung zur Heilung der verschiedensten Krankheiten"},"content":{"rendered":"<table width=\"\" cellpadding=\"\" border=\"\">\n<tbody>\n<tr>\n<td valign=\"\">\n<div class=\"\">\n<h2>Der Lebensmagnetismus seine Erscheinungen und seine Praxis<\/h2>\n<h3>Seine Anwendung zur Heilung der verschiedensten Krankheiten<\/h3>\n<p class=\"\">von Dr. med. Georg Barth<\/p>\n<\/div>\n<p class=\"\">ISBN 978-3-89094-677-1 (ISBN10 3-89094-677-1),<br \/>168 Seiten, Softcover, Format DIN-A5 <br \/>1. Auflage\u00a0\u00a0\n<\/p>\n<\/td>\n<td align=\"\" class=\"\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <\/p>\n<h3 class=\"\">Buchbeschreibung:<\/h3>\n<p alt=\"\" class=\"\">Die<br \/>\n Kunst des Magnetismus wurde schon in fr\u00fchester Zeit ausge\u00fcbt und als<br \/>\nerfolgreiche Therapie angewendet. Das Heilen durch Handauflegen,<br \/>\nAstrales oder Magnetisches Heilen und andere Energie\u00fcbertragungen, wie<br \/>\nauch durch Reiki und Chi-Energie, hat auf der ganzen Welt und in allen<br \/>\nL\u00e4ndern eine sehr lange Tradition.<br \/>\nInzwischen wird auch das Handauflegen wieder angewendet, da ihre<br \/>\nHeilungsergebnisse, gerade in Zusammenhang mit der normalen<br \/>\nKrankenhausmedizin (haupts\u00e4chlich in England, den USA, den Niederlanden<br \/>\nund \u00d6sterreich) f\u00fcr sich sprechen. Wenn auch bis heute nicht genau<br \/>\ngekl\u00e4rt werden konnte, wie es funktioniert &#8211; eines ist sicher: Wer heilt<br \/>\n hat recht.<\/p>\n<p alt=\"\" class=\"\">\nDer Autor beschreibt in diesem Buch Wesen, Erscheinen und Anwendung des<br \/>\nLebensmagnetismus. Er schildert eigene Erfahrungen und gibt ausf\u00fchrliche<br \/>\n praxisnahe Anleitungen zu den verschiedenen Arten des Magnetisierens.<\/p>\n<ul>\n<li>Anmerkungen des Verlages<\/li>\n<li>Vorwort und Einleitung<\/li>\n<ul>\n<li>Vorwort<\/li>\n<li>Einleitung<\/li>\n<\/ul>\n<li>Geschichte des Magnetismus<\/li>\n<li>\u00dcber magnetische Zust\u00e4nde<\/li>\n<li>Der magnetische Schlaf<\/li>\n<li>Der wache magnetische Zustand<\/li>\n<li>Der schlafwache magnetische Zustand<\/li>\n<ul>\n<li>Der medizinische Instinkt<\/li>\n<li>Das Einw\u00e4rtssehen oder Nach-innen-Sehen<\/li>\n<li>Nachhersehen und Vorhersehen oder Weissagung<\/li>\n<li>Die Verz\u00fcckung oder Ekstase<\/li>\n<\/ul>\n<li>Einzelne Erscheinungen<\/li>\n<ul>\n<li>Herziehung<\/li>\n<li>Katalepsie<\/li>\n<li>Steifheit<\/li>\n<li>Scheinbare Anh\u00e4ngung<\/li>\n<li>Transposition der Sinne<\/li>\n<li>Phrenomagnetismus<\/li>\n<li>Nerven- und Gehirnsympathie oder \u00dcbertragung der Empfindungen und Gedanken<\/li>\n<li>Herrschaft des Willens<\/li>\n<li>Das magnetische Versprechen<\/li>\n<li>Magnetische Anziehung<\/li>\n<\/ul>\n<li>Das magnetische Verfahren<\/li>\n<ul>\n<li>Die magnetischen Striche<\/li>\n<li>Das Entmagnetisieren oder Wecken<\/li>\n<li>Von der Dauer magnetischer Zust\u00e4nde<\/li>\n<\/ul>\n<li>Von der magnetischen Empf\u00e4nglichkeit<\/li>\n<li>\u00dcber Magnetisierung lebloser Gegenst\u00e4nde<\/li>\n<li>Von den Gefahren bei der Anwendung der magnetischen Kraft<\/li>\n<li>Die Kreuzmagnetisierung<\/li>\n<li>Die Isolierung<\/li>\n<li>Das magnetische Delirium oder der magnetische Traum<\/li>\n<li>\u00dcber die Anwendung des Lebensmagnetismus gegen Krankheiten<\/li>\n<li>Die Di\u00e4t<\/li>\n<li>Vorsichtige Behandlung von Hellsehern<\/li>\n<li>Von den Magnetisierern<\/li>\n<li>Anhang<\/li>\n<ul>\n<li>Hypnotismus (Somnambulismus) und Elektrobiologie<\/li>\n<p alt=\"\">\n<span class=\"\">ISBN 978-3-89094-677-1, 168 Seiten, Softcover, Format DIN-A5<\/span><\/p>\n<\/ul>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Der Lebensmagnetismus seine Erscheinungen und seine Praxis Seine Anwendung zur Heilung der verschiedensten Krankheiten von Dr. med. Georg Barth ISBN 978-3-89094-677-1 (ISBN10 3-89094-677-1),168 Seiten, Softcover, Format DIN-A5 1. Auflage\u00a0\u00a0 Buchbeschreibung: Die Kunst des Magnetismus wurde schon in fr\u00fchester Zeit ausge\u00fcbt und als erfolgreiche Therapie angewendet. Das Heilen durch Handauflegen, Astrales oder Magnetisches Heilen und andere [&hellip;]<\/p>\n","protected":false},"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[47],"product_tag":[],"_links":{"self":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product\/10380"}],"collection":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/comments?post=10380"}],"wp:attachment":[{"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/media?parent=10380"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product_cat?post=10380"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/andromeda-buecher.de\/buch2\/wp-json\/wp\/v2\/product_tag?post=10380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}